{"id":8795,"date":"2021-12-13T11:05:00","date_gmt":"2021-12-13T10:05:00","guid":{"rendered":"https:\/\/chiavalon.hr\/non-categorizzato\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/"},"modified":"2026-03-24T13:34:57","modified_gmt":"2026-03-24T12:34:57","slug":"chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2","status":"publish","type":"post","link":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/","title":{"rendered":"Chiavalon &amp; Co. vi augura un Buon Natale e un Felice Anno Nuovo \ud83d\ude0a"},"content":{"rendered":"\n<p>Cari amici, un altro anno \u00e8 arrivato alla fine. Questo \u00e8 il momento in cui sommiamo i pro e i contro, misuriamo quanto abbiamo fatto, cosa faremmo meglio e dove abbiamo margine di progresso. Siamo orgogliosi di tutti i nostri dipendenti che hanno fatto un ottimo lavoro durante tutto l&#8217;anno, ed \u00e8 grazie a loro che ogni anno facciamo un passo avanti nel nostro lavoro.<\/p>\n\n\n\n<p>\u00c8 arrivato ora pi\u00f9 che meritato il tempo delle vacanze. Vi informiamo che lavoreremo e spediremo i vostri pacchi fino al 23 dicembre e torneremo al lavoro il 10 gennaio 2022.  Durante le vacanze il nostro webshop funzioner\u00e0 normalmente, tutti gli ordini saranno accettati e spediti da noi al ritorno al lavoro dal 10 gennaio.<\/p>\n\n\n\n<p>Nel frattempo, vi auguriamo tutto il meglio per le prossime feste. Siate sani, circondati da persone che diffondono positivit\u00e0 e amore e realizzate tutto quello che avete immaginato nel 2022.<\/p>\n\n\n\n<p>Vi auguriamo ricche tavole festive con buon cibo, buone bevande e se il tutto \u00e8 condito con una goccia del nostro olio, saremo felici di far parte delle vostre festivit\u00e0`.<\/p>\n\n\n\n<p>Grazie per il sostegno, la fedelt\u00e0 e l&#8217;amore che ci avete dato durante l&#8217;anno. Promettiamo di fare del nostro meglio per meritarlo di nuovo l&#8217;anno prossimo!<\/p>\n\n\n\n<p>La vostra famiglia Chiavalon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cari amici, un altro anno \u00e8 arrivato alla fine. Questo \u00e8 il momento in cui sommiamo i pro e i contro, misuriamo quanto abbiamo fatto, cosa faremmo meglio e dove abbiamo margine di progresso. Siamo orgogliosi di tutti i nostri dipendenti che hanno fatto un ottimo lavoro durante tutto l&#8217;anno, ed \u00e8 grazie a loro [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":8673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[139,82],"tags":[],"class_list":["post-8795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buon Natale e felice Anno Nuovo | Chiavalon<\/title>\n<meta name=\"description\" content=\"Buon Natale dalla famiglia Chiavalon! Controllate gli orari del negozio online e arricchite la tavola delle feste con il nostro olio extravergine di oliva.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buon Natale e felice Anno Nuovo | Chiavalon\" \/>\n<meta property=\"og:description\" content=\"Buon Natale dalla famiglia Chiavalon! Controllate gli orari del negozio online e arricchite la tavola delle feste con il nostro olio extravergine di oliva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Chiavalon\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-13T10:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T12:34:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"order\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"order\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/\",\"url\":\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/\",\"name\":\"Buon Natale e felice Anno Nuovo | Chiavalon\",\"isPartOf\":{\"@id\":\"https:\/\/chiavalon.hr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp\",\"datePublished\":\"2021-12-13T10:05:00+00:00\",\"dateModified\":\"2026-03-24T12:34:57+00:00\",\"author\":{\"@id\":\"https:\/\/chiavalon.hr\/#\/schema\/person\/828bab9ec632778a44fddbbf316f9dfc\"},\"description\":\"Buon Natale dalla famiglia Chiavalon! Controllate gli orari del negozio online e arricchite la tavola delle feste con il nostro olio extravergine di oliva.\",\"breadcrumb\":{\"@id\":\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#primaryimage\",\"url\":\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp\",\"contentUrl\":\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/chiavalon.hr\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiavalon &amp; Co. vi augura un Buon Natale e un Felice Anno Nuovo \ud83d\ude0a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chiavalon.hr\/#website\",\"url\":\"https:\/\/chiavalon.hr\/\",\"name\":\"Chiavalon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chiavalon.hr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/chiavalon.hr\/#\/schema\/person\/828bab9ec632778a44fddbbf316f9dfc\",\"name\":\"order\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/chiavalon.hr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/768a2359e2c34100c684958b030df7f3ca3fd2a3a7c792ead2a84f3939c68de8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/768a2359e2c34100c684958b030df7f3ca3fd2a3a7c792ead2a84f3939c68de8?s=96&d=mm&r=g\",\"caption\":\"order\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buon Natale e felice Anno Nuovo | Chiavalon","description":"Buon Natale dalla famiglia Chiavalon! Controllate gli orari del negozio online e arricchite la tavola delle feste con il nostro olio extravergine di oliva.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/","og_locale":"it_IT","og_type":"article","og_title":"Buon Natale e felice Anno Nuovo | Chiavalon","og_description":"Buon Natale dalla famiglia Chiavalon! Controllate gli orari del negozio online e arricchite la tavola delle feste con il nostro olio extravergine di oliva.","og_url":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/","og_site_name":"Chiavalon","article_published_time":"2021-12-13T10:05:00+00:00","article_modified_time":"2026-03-24T12:34:57+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp","type":"image\/webp"}],"author":"order","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"order","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/","url":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/","name":"Buon Natale e felice Anno Nuovo | Chiavalon","isPartOf":{"@id":"https:\/\/chiavalon.hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#primaryimage"},"image":{"@id":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#primaryimage"},"thumbnailUrl":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp","datePublished":"2021-12-13T10:05:00+00:00","dateModified":"2026-03-24T12:34:57+00:00","author":{"@id":"https:\/\/chiavalon.hr\/#\/schema\/person\/828bab9ec632778a44fddbbf316f9dfc"},"description":"Buon Natale dalla famiglia Chiavalon! Controllate gli orari del negozio online e arricchite la tavola delle feste con il nostro olio extravergine di oliva.","breadcrumb":{"@id":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#primaryimage","url":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp","contentUrl":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/12\/ezgif.com-gif-maker.webp","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/chiavalon.hr\/it\/notizie\/chiavalon-co-wishes-you-a-merry-christmas-and-a-happy-new-year-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiavalon.hr\/it\/"},{"@type":"ListItem","position":2,"name":"Chiavalon &amp; Co. vi augura un Buon Natale e un Felice Anno Nuovo \ud83d\ude0a"}]},{"@type":"WebSite","@id":"https:\/\/chiavalon.hr\/#website","url":"https:\/\/chiavalon.hr\/","name":"Chiavalon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiavalon.hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/chiavalon.hr\/#\/schema\/person\/828bab9ec632778a44fddbbf316f9dfc","name":"order","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/chiavalon.hr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/768a2359e2c34100c684958b030df7f3ca3fd2a3a7c792ead2a84f3939c68de8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/768a2359e2c34100c684958b030df7f3ca3fd2a3a7c792ead2a84f3939c68de8?s=96&d=mm&r=g","caption":"order"}}]}},"_links":{"self":[{"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/posts\/8795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/comments?post=8795"}],"version-history":[{"count":0,"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/posts\/8795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/media\/8673"}],"wp:attachment":[{"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/media?parent=8795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/categories?post=8795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiavalon.hr\/it\/wp-json\/wp\/v2\/tags?post=8795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}