{"id":8809,"date":"2021-11-11T11:09:00","date_gmt":"2021-11-11T10:09:00","guid":{"rendered":"https:\/\/chiavalon.hr\/unkategorisiert\/5-reasons-why-you-should-visit-us\/"},"modified":"2026-03-26T11:38:00","modified_gmt":"2026-03-26T10:38:00","slug":"5-reasons-why-you-should-visit-us","status":"publish","type":"post","link":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/","title":{"rendered":"5 Gr\u00fcnde, warum Sie uns besuchen sollten"},"content":{"rendered":"\n<p>Unsere Mischungen geh\u00f6ren zu den meistausgezeichneten der Welt, was aber nicht der einzige Grund ist, warum die Leute zu uns zur Verkostung kommen. Wir sind stolz auf unsere Arbeitsweise, unsere Familie und unsere Vision. Wir treiben uns selbst voran und das ist die Geschichte, die wir auch Ihnen erz\u00e4hlen m\u00f6chten.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong><strong>WIR SIND KEIN GEW\u00d6HNLICHER \u00d6LHERSTELLER.<\/strong><\/strong><\/li>\n<\/ol>\n\n\n\n<p>Wir begannen unsere Geschichte 1997 mit etwa 50 Olivenb\u00e4umen. heute haben wir fast 9000 davon. Wir haben studiert, uns weitergebildet und uns in diese Geschichte hineingesteigert. Unsere ganze Familie steckt in jedem Meter unserer Oliven\u00f6lm\u00fchle, in jedem Tropfen unseres \u00d6ls und das ist unsere Leidenschaft &#8211; zu lernen, zu arbeiten, die Qualit\u00e4t zu verbessern und die Geschichte von Tradition und Technologie im Einklang mit der Produktion von nativem Oliven\u00f6l extra zu erz\u00e4hlen. Wir haben uns nie um Quantit\u00e4t gesorgt, sondern um Qualit\u00e4t. Und wir wissen immer, dass es noch besser werden kann, und wir arbeiten st\u00e4ndig daran.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong><strong>WIR MACHEN DIE DINGE AUF EINE ANDERE ART. UNSERE ART.<\/strong><\/strong><\/li>\n<\/ol>\n\n\n\n<p>Wir haben uns ganz bewusst um neue Produktionsmethoden bem\u00fcht, um nur die beste Qualit\u00e4t von nativem Oliven\u00f6l extra zu garantieren. Wir ernten die Oliven fr\u00fcher als andere Hersteller, unsere Verarbeitungsmaschinen sind die modernsten in Europa und wir stellen spezielle Mischungen aus jeder Sorte her, damit wir die Qualit\u00e4t unseres \u00d6ls das ganze Jahr \u00fcber beibehalten k\u00f6nnen. Unsere Oliven\u00f6lm\u00fchle ist das Herzst\u00fcck unserer Marke &#8211; dort sind wir alle zusammen, wir verarbeiten Oliven, wir f\u00fcllen \u00d6l in Flaschen ab, dort ist unser Laden und dort sind wir mit Ihnen zusammen.<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong><strong>UNSER \u00d6L GEH\u00d6RT ZU DEN TOP 15 DER BESTEN \u00d6LE DER WELT.<\/strong><\/strong><\/li>\n<\/ol>\n\n\n\n<p>Wir sind seit Jahren in zahlreichen Reisef\u00fchrern vertreten und erhalten Auszeichnungen f\u00fcr unsere \u00d6le. Die meisten Michelin-Sternerestaurants in Kroatien verwenden unsere \u00d6le. Wir sind stolz auf unseren Erfolg und all die M\u00fchen, Opfer und Entbehrungen, die dahinter stecken. Unsere gr\u00f6\u00dfte Belohnung ist jedoch unsere Zufriedenheit, die positiven Kommentare der Menschen, denen wir jeden Tag begegnen, die Ideen, die wir verwirklichen und die Projekte, die nicht aufh\u00f6ren.<\/p>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong><strong>UNSERE VERKOSTUNGEN SIND LEHRREICH, WIR MACHEN SIE F\u00dcR SIE.<\/strong><\/strong><\/li>\n<\/ol>\n\n\n\n<p>Wir f\u00fchren jeden Tag Verkostungen in unserer Oliven\u00f6lm\u00fchle durch. Wir bieten drei Verkostungserlebnisse an &#8211; je nachdem, wie viel Zeit Sie zur Verf\u00fcgung haben und was Sie probieren und lernen m\u00f6chten. Unsere Idee ist es, Ihnen beizubringen, wie das \u00d6l hergestellt wird, wie Sie echtes natives Oliven\u00f6l extra von falschen \u00d6len unterscheiden k\u00f6nnen, Ihnen Tipps zur Verwendung des \u00d6ls zu geben und aus erster Hand zu erfahren, wie das \u00d6l mit Speisen und Getr\u00e4nken kombiniert wird und wie sehr es jede gastronomische Geschichte bereichert.<\/p>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li><strong><strong>WIR SIND EINE \u00d6KO-MARKE. IN JEDEM SCHRITT UNSERER GESCHICHTE<\/strong><\/strong><\/li>\n<\/ol>\n\n\n\n<p>Unsere gesamte Produktion steht unter zertifizierter \u00f6kologischer Kontrolle. Wir sind sehr stolz darauf, dass unser natives Oliven\u00f6l extra das Bio-Siegel und die gesch\u00fctzte Ursprungsbezeichnung tr\u00e4gt, die garantieren und sicherstellen, dass es sich um zertifiziertes 100% biologisches natives Oliven\u00f6l extra aus Istrien handelt. Neben dem \u00d6l sind wir auch in der Landwirtschaft t\u00e4tig. Die Bio-Tomatenpassata ist unser erstes Endprodukt, das direkt von den Feldern im Tal des Flusses Ra\u0161a stammt. Die biologisch angebauten Tomaten werden in der Regel fr\u00fch am Morgen geerntet und erst nach ein paar Stunden in eine schmackhafte Tomatenpassata verwandelt.<\/p>\n\n\n\n<p>Wenn Sie all das, was wir Ihnen erz\u00e4hlt haben, aus erster Hand erfahren m\u00f6chten, nehmen Sie Kontakt mit uns auf und buchen Sie Ihre Verkostung, wir warten auf Sie.<\/p>\n\n\n\n<p><strong>Mehr Informationen:<\/strong><\/p>\n\n\n\n<p>Online-Reservierungen k\u00f6nnen nicht f\u00fcr Besuche am selben Tag vorgenommen werden.<\/p>\n\n\n\n<p>Letzte Buchungsanfragen f\u00fcr Besuche am n\u00e4chsten Tag sind bis 18 Uhr m\u00f6glich.<\/p>\n\n\n\n<p>Wenn Sie ein privates, ma\u00dfgeschneidertes Programm bevorzugen, kontaktieren Sie uns bitte unter visit@chiavalon.hr<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Wir sind ge\u00f6ffnet<\/strong><\/p>\n\n\n\n<p>10 Uhr bis 18 Uhr &#8211; Montag bis Freitag<\/p>\n\n\n\n<p>An Sams-, Sonn- und Feiertagen haben wir geschlossen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere Mischungen geh\u00f6ren zu den meistausgezeichneten der Welt, was aber nicht der einzige Grund ist, warum die Leute zu uns zur Verkostung kommen. Wir sind stolz auf unsere Arbeitsweise, unsere Familie und unsere Vision. Wir treiben uns selbst voran und das ist die Geschichte, die wir auch Ihnen erz\u00e4hlen m\u00f6chten. Wir begannen unsere Geschichte 1997 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[138,83],"tags":[],"class_list":["post-8809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 Gr\u00fcnde, uns in Vodnjan zu besuchen | Chiavalon<\/title>\n<meta name=\"description\" content=\"Besuchen Sie Chiavalon in Vodnjan, Istrien! Reservieren Sie lehrreiche Verkostungen und erfahren Sie, warum unser natives Oliven\u00f6l extra zu den 15 besten der Welt geh\u00f6rt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Gr\u00fcnde, uns in Vodnjan zu besuchen | Chiavalon\" \/>\n<meta property=\"og:description\" content=\"Besuchen Sie Chiavalon in Vodnjan, Istrien! Reservieren Sie lehrreiche Verkostungen und erfahren Sie, warum unser natives Oliven\u00f6l extra zu den 15 besten der Welt geh\u00f6rt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Chiavalon\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T10:09:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T10:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1094\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"ivanpercan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ivanpercan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/\",\"url\":\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/\",\"name\":\"5 Gr\u00fcnde, uns in Vodnjan zu besuchen | Chiavalon\",\"isPartOf\":{\"@id\":\"https:\/\/chiavalon.hr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp\",\"datePublished\":\"2021-11-11T10:09:00+00:00\",\"dateModified\":\"2026-03-26T10:38:00+00:00\",\"author\":{\"@id\":\"https:\/\/chiavalon.hr\/#\/schema\/person\/c55a999ad65fce98eb4e1a651320a0c7\"},\"description\":\"Besuchen Sie Chiavalon in Vodnjan, Istrien! Reservieren Sie lehrreiche Verkostungen und erfahren Sie, warum unser natives Oliven\u00f6l extra zu den 15 besten der Welt geh\u00f6rt.\",\"breadcrumb\":{\"@id\":\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#primaryimage\",\"url\":\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp\",\"contentUrl\":\"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp\",\"width\":1094,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/chiavalon.hr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Gr\u00fcnde, warum Sie uns besuchen sollten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chiavalon.hr\/#website\",\"url\":\"https:\/\/chiavalon.hr\/\",\"name\":\"Chiavalon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chiavalon.hr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/chiavalon.hr\/#\/schema\/person\/c55a999ad65fce98eb4e1a651320a0c7\",\"name\":\"ivanpercan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/chiavalon.hr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7167006268c65fbf33759443d10d826f29b912acae0ee815d28c2e67186e37bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7167006268c65fbf33759443d10d826f29b912acae0ee815d28c2e67186e37bc?s=96&d=mm&r=g\",\"caption\":\"ivanpercan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Gr\u00fcnde, uns in Vodnjan zu besuchen | Chiavalon","description":"Besuchen Sie Chiavalon in Vodnjan, Istrien! Reservieren Sie lehrreiche Verkostungen und erfahren Sie, warum unser natives Oliven\u00f6l extra zu den 15 besten der Welt geh\u00f6rt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/","og_locale":"de_DE","og_type":"article","og_title":"5 Gr\u00fcnde, uns in Vodnjan zu besuchen | Chiavalon","og_description":"Besuchen Sie Chiavalon in Vodnjan, Istrien! Reservieren Sie lehrreiche Verkostungen und erfahren Sie, warum unser natives Oliven\u00f6l extra zu den 15 besten der Welt geh\u00f6rt.","og_url":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/","og_site_name":"Chiavalon","article_published_time":"2021-11-11T10:09:00+00:00","article_modified_time":"2026-03-26T10:38:00+00:00","og_image":[{"width":1094,"height":627,"url":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp","type":"image\/webp"}],"author":"ivanpercan","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"ivanpercan","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/","url":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/","name":"5 Gr\u00fcnde, uns in Vodnjan zu besuchen | Chiavalon","isPartOf":{"@id":"https:\/\/chiavalon.hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#primaryimage"},"image":{"@id":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#primaryimage"},"thumbnailUrl":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp","datePublished":"2021-11-11T10:09:00+00:00","dateModified":"2026-03-26T10:38:00+00:00","author":{"@id":"https:\/\/chiavalon.hr\/#\/schema\/person\/c55a999ad65fce98eb4e1a651320a0c7"},"description":"Besuchen Sie Chiavalon in Vodnjan, Istrien! Reservieren Sie lehrreiche Verkostungen und erfahren Sie, warum unser natives Oliven\u00f6l extra zu den 15 besten der Welt geh\u00f6rt.","breadcrumb":{"@id":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#primaryimage","url":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp","contentUrl":"https:\/\/chiavalon.hr\/wp-content\/uploads\/2021\/11\/59-scaled-e1638408341497.webp","width":1094,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/chiavalon.hr\/de\/blog\/5-reasons-why-you-should-visit-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiavalon.hr\/de\/"},{"@type":"ListItem","position":2,"name":"5 Gr\u00fcnde, warum Sie uns besuchen sollten"}]},{"@type":"WebSite","@id":"https:\/\/chiavalon.hr\/#website","url":"https:\/\/chiavalon.hr\/","name":"Chiavalon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiavalon.hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/chiavalon.hr\/#\/schema\/person\/c55a999ad65fce98eb4e1a651320a0c7","name":"ivanpercan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/chiavalon.hr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7167006268c65fbf33759443d10d826f29b912acae0ee815d28c2e67186e37bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7167006268c65fbf33759443d10d826f29b912acae0ee815d28c2e67186e37bc?s=96&d=mm&r=g","caption":"ivanpercan"}}]}},"_links":{"self":[{"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/posts\/8809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/comments?post=8809"}],"version-history":[{"count":0,"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/posts\/8809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/media\/8632"}],"wp:attachment":[{"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/media?parent=8809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/categories?post=8809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiavalon.hr\/de\/wp-json\/wp\/v2\/tags?post=8809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}